{"id":16276,"date":"2023-06-10T02:02:17","date_gmt":"2023-06-10T01:02:14","guid":{"rendered":"https:\/\/swiss-peak.com\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/"},"modified":"2026-04-16T03:06:23","modified_gmt":"2026-04-16T01:06:23","slug":"paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro","status":"publish","type":"product","link":"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/","title":{"rendered":"Paraguas contra tormentas AWARE\u2122 Tornado de 23\u201d, negro"},"content":{"rendered":"<p>El paraguas contra tormentas Swiss Peak AWARE\u2122 Tornado de 23 pulgadas cuenta con RPET pongee 190T y es un accesorio de primera calidad dise\u00f1ado para condiciones clim\u00e1ticas adversas. Su sistema de apertura autom\u00e1tica\/cierre manual y a prueba de viento proporciona facilidad de uso y confiabilidad. Con un eje de metal y un marco completo de fibra de vidrio, este paraguas ofrece resistencia y durabilidad. El mango recto con acabado de goma ABS es c\u00f3modo de agarrar y viene con una caja de regalo de papel kraft Swiss Peak FSC. Con trazador AWARE\u2122 que valida el uso genuino de materiales reciclados. El 2% de las ganancias de cada producto Aware\u2122 vendido se donar\u00e1 a Water.org.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El paraguas contra tormentas Swiss Peak AWARE\u2122 Tornado de 23 pulgadas cuenta con RPET pongee 190T y es un accesorio de primera calidad dise\u00f1ado para condiciones clim\u00e1ticas adversas. Su sistema de apertura autom\u00e1tica\/cierre manual y a prueba de viento proporciona facilidad de uso y confiabilidad. Con un eje de metal y un marco completo de [&hellip;]<\/p>\n","protected":false},"featured_media":46608,"template":"","meta":{"_acf_changed":false},"product_cat":[309,321],"product_tag":[],"class_list":["post-16276","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-ocio-deporte","product_cat-paraguas","pa_color-black-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paraguas contra tormentas AWARE\u2122 Tornado de 23\u201d, negro - Swiss Peak<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paraguas contra tormentas AWARE\u2122 Tornado de 23\u201d, negro - Swiss Peak\" \/>\n<meta property=\"og:description\" content=\"El paraguas contra tormentas Swiss Peak AWARE\u2122 Tornado de 23 pulgadas cuenta con RPET pongee 190T y es un accesorio de primera calidad dise\u00f1ado para condiciones clim\u00e1ticas adversas. Su sistema de apertura autom\u00e1tica\/cierre manual y a prueba de viento proporciona facilidad de uso y confiabilidad. Con un eje de metal y un marco completo de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/\" \/>\n<meta property=\"og:site_name\" content=\"Swiss Peak\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T01:06:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swiss-peak.com\/wp-content\/uploads\/sites\/9\/2026\/04\/P850.471__S_0__1b17ca2b6ae04fa8a858a836cdf80c1c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/\",\"url\":\"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/\",\"name\":\"Paraguas contra tormentas AWARE\u2122 Tornado de 23\u201d, negro - Swiss Peak\",\"isPartOf\":{\"@id\":\"https:\/\/swiss-peak.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/swiss-peak.com\/wp-content\/uploads\/sites\/9\/2026\/04\/P850.471__S_0__1b17ca2b6ae04fa8a858a836cdf80c1c.jpg\",\"datePublished\":\"2023-06-10T01:02:14+00:00\",\"dateModified\":\"2026-04-16T01:06:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/#primaryimage\",\"url\":\"https:\/\/swiss-peak.com\/wp-content\/uploads\/sites\/9\/2026\/04\/P850.471__S_0__1b17ca2b6ae04fa8a858a836cdf80c1c.jpg\",\"contentUrl\":\"https:\/\/swiss-peak.com\/wp-content\/uploads\/sites\/9\/2026\/04\/P850.471__S_0__1b17ca2b6ae04fa8a858a836cdf80c1c.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/swiss-peak.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colecci\u00f3n\",\"item\":\"https:\/\/swiss-peak.com\/es\/coleccion\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Paraguas contra tormentas AWARE\u2122 Tornado de 23\u201d, negro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/swiss-peak.com\/es\/#website\",\"url\":\"https:\/\/swiss-peak.com\/es\/\",\"name\":\"Swiss Peak\",\"description\":\"Where will today take you?\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/swiss-peak.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paraguas contra tormentas AWARE\u2122 Tornado de 23\u201d, negro - Swiss Peak","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/","og_locale":"es_ES","og_type":"article","og_title":"Paraguas contra tormentas AWARE\u2122 Tornado de 23\u201d, negro - Swiss Peak","og_description":"El paraguas contra tormentas Swiss Peak AWARE\u2122 Tornado de 23 pulgadas cuenta con RPET pongee 190T y es un accesorio de primera calidad dise\u00f1ado para condiciones clim\u00e1ticas adversas. Su sistema de apertura autom\u00e1tica\/cierre manual y a prueba de viento proporciona facilidad de uso y confiabilidad. Con un eje de metal y un marco completo de [&hellip;]","og_url":"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/","og_site_name":"Swiss Peak","article_modified_time":"2026-04-16T01:06:23+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/swiss-peak.com\/wp-content\/uploads\/sites\/9\/2026\/04\/P850.471__S_0__1b17ca2b6ae04fa8a858a836cdf80c1c.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/","url":"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/","name":"Paraguas contra tormentas AWARE\u2122 Tornado de 23\u201d, negro - Swiss Peak","isPartOf":{"@id":"https:\/\/swiss-peak.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/#primaryimage"},"image":{"@id":"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/#primaryimage"},"thumbnailUrl":"https:\/\/swiss-peak.com\/wp-content\/uploads\/sites\/9\/2026\/04\/P850.471__S_0__1b17ca2b6ae04fa8a858a836cdf80c1c.jpg","datePublished":"2023-06-10T01:02:14+00:00","dateModified":"2026-04-16T01:06:23+00:00","breadcrumb":{"@id":"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/#primaryimage","url":"https:\/\/swiss-peak.com\/wp-content\/uploads\/sites\/9\/2026\/04\/P850.471__S_0__1b17ca2b6ae04fa8a858a836cdf80c1c.jpg","contentUrl":"https:\/\/swiss-peak.com\/wp-content\/uploads\/sites\/9\/2026\/04\/P850.471__S_0__1b17ca2b6ae04fa8a858a836cdf80c1c.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/swiss-peak.com\/es\/producto\/paraguas-contra-tormentas-swiss-peak-aware-tornado-de-23-negro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiss-peak.com\/es\/"},{"@type":"ListItem","position":2,"name":"Colecci\u00f3n","item":"https:\/\/swiss-peak.com\/es\/coleccion\/"},{"@type":"ListItem","position":3,"name":"Paraguas contra tormentas AWARE\u2122 Tornado de 23\u201d, negro"}]},{"@type":"WebSite","@id":"https:\/\/swiss-peak.com\/es\/#website","url":"https:\/\/swiss-peak.com\/es\/","name":"Swiss Peak","description":"Where will today take you?","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiss-peak.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/swiss-peak.com\/es\/wp-json\/wp\/v2\/product\/16276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiss-peak.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/swiss-peak.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swiss-peak.com\/es\/wp-json\/wp\/v2\/media\/46608"}],"wp:attachment":[{"href":"https:\/\/swiss-peak.com\/es\/wp-json\/wp\/v2\/media?parent=16276"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/swiss-peak.com\/es\/wp-json\/wp\/v2\/product_cat?post=16276"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/swiss-peak.com\/es\/wp-json\/wp\/v2\/product_tag?post=16276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}